{"id":3420,"date":"2022-07-06T18:00:00","date_gmt":"2022-07-06T16:00:00","guid":{"rendered":"https:\/\/ancestrallyhealthy.com\/?p=3420"},"modified":"2023-07-03T14:24:25","modified_gmt":"2023-07-03T12:24:25","slug":"gesaettigte-fette","status":"publish","type":"post","link":"https:\/\/ancestrallyhealthy.com\/de\/gesaettigte-fette\/","title":{"rendered":"Ges\u00e4ttigte Fette &#8211; warum wir die Falschen angeprangert haben!"},"content":{"rendered":"<p>Ges\u00e4ttigte Fette waren lange Zeit bekannt als direkt herzsch\u00e4dlich. Wir verdanken diese Sicht einer Reihe von fraglichen Studien der 70er. Trotz des Alters ist der Gedanke immer noch vorhanden in modernen Verst\u00e4nden. Wie wir sp\u00e4ter sehen werden, existiert eine Menge an Geschichte zu diesem Thema, mit Stars wie Dwight Eisenhower, die <em>den Werdegang dieser Stoffgruppe stark beeinflusst haben.<\/em><\/p><p>Das R\u00e4tsel f\u00fcr mich und der Anfang meiner Reise in dieses Thema war die Frage:<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Warum sollen ges\u00e4ttigte Fette aus Tieren <em>sch\u00e4dlich <\/em>sein, wenn sie vor dem Jahr ~1900, vor der <em>Erfindung <\/em>von Pflanzen\u00f6len, das <em>einzige <\/em>Fett waren, das wir Menschen a\u00dfen, seit <em>Millionen <\/em>von Jahren?<\/p><\/blockquote><p>Seitdem an ist der Konsum von mehrfach-unges\u00e4ttigten Fetten explodiert, wie auch chronische Krankheiten aller Art. Zufall? Und genau die erste Frage wollen wir in diesem Artikel beantworten &#8211; <strong>wie kann etwas nat\u00fcrliches sch\u00e4dlich sein und k\u00fcnstlicher Industrieabfall besser? <\/strong>Da stimmt etwas nicht. Aber dazu sp\u00e4ter mehr.<\/p><p>Falls Du den ersten Teil \u00fcber mehrfach-unges\u00e4ttigte Fette, deren Biochemie und Probleme in menschlicher Ern\u00e4hrung, sowie Tipps zum Umgang in Deiner Ern\u00e4hrung noch nicht gelesen hast, <a href=\"https:\/\/ancestrallyhealthy.com\/mehrfach-ungesattigte-fette\/\" data-type=\"post\" data-id=\"3405\">findest Du ihn hier.<\/a><\/p><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h2 class=\"wp-block-heading has-text-align-center\" id=\"what-are-saturated-fats\"><span style=\"text-decoration: underline;\">Was sind Ges\u00e4ttigte Fette?<\/span><\/h2><h3 class=\"wp-block-heading\" id=\"a-quick-recap-on-saturation\"><span style=\"text-decoration: underline;\">EIn kurzer Recap zur S\u00e4ttigung<\/span><\/h3><p>Dieses Thema ist im ersten PUFA Artikel in L\u00e4nge ausgef\u00fchrt, deshalb schau bitte dort nach f\u00fcr eine genauere Erkl\u00e4rung. S\u00e4ttigung hat mit den Verbindungen zu tun, zwischen den einzelnen Kohlenstoffatomen der Fetts\u00e4urenkette.<\/p><p>Zusammenfassend haben wir gesehen, dass:<\/p><ul class=\"wp-block-list\"><li>Ges\u00e4ttigte Fette, wie der Name sagt, sind voll oder ges\u00e4ttigt, <strong>sie haben nur Doppelverbindungen<\/strong> zwischen den Atomen.<\/li>\n\n<li>Einfach unges\u00e4ttigte Fetts\u00e4uren <strong>haben eine Einfachbindung<\/strong><\/li>\n\n<li>Mehrfach-unges\u00e4ttigte Fetts\u00e4uren <strong>haben mehrere<\/strong> <strong>Einfachbindungen <\/strong>an verschiedenen Stellen ihrer Ketten<\/li>\n\n<li><strong>Ges\u00e4ttigte sind daher gl\u00fccklich &amp; reaktionsfaul, mehrfach-unges\u00e4ttigte sehr instabil.<\/strong><\/li><\/ul><div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"wp-block-heading\" id=\"the-story-of-saturated-fats\"><span style=\"text-decoration: underline;\">Der S\u00fcndenfall der Ges\u00e4ttigten Fette<\/span><\/h3><h4 class=\"wp-block-heading\">Eisenhowers Herzinfarkt<\/h4><p>Um das Thema im Kontext zu verstehen, m\u00fcssen wir uns zuerst die Umst\u00e4nde anschauen, wie eine Stoffgruppe verteufelt werden konnte. So k\u00f6nnen wir sehen,<strong> woher die Empfehlung kam f\u00fcr Pflanzen\u00f6le und was die Argumente sind.<\/strong><\/p><div class=\"wp-block-image\"><figure class=\"alignright size-medium\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-300x199.jpg\" alt=\"Cheese and dairy can be great foods if your body doesn&#039;t react to them. Otherwise, eating cheese can be ancestrally consistent and beneficial rich in saturated fats.\" class=\"wp-image-3423\" title=\"\" srcset=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-300x199.jpg 300w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-600x399.jpg 600w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-1024x681.jpg 1024w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-768x510.jpg 768w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-828x550.jpg 828w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-1060x704.jpg 1060w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-1536x1021.jpg 1536w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-550x366.jpg 550w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-752x500.jpg 752w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product-1625x1080.jpg 1625w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Cheese-an-animal-dairy-product.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Actually, for most of history saturates were fine, as they were the most abundant fats around.<\/figcaption><\/figure><\/div><p>Die Journalistin Nina Teichholz hat einen gro\u00dfartigen Job gemacht und das ganze Thema<a class=\"thirstylink\" rel=\"nofollow noopener\" target=\"_blank\" title=\"Nina Teichholz&#039; Big Fat Surprise\" href=\"https:\/\/amzn.to\/3v68WJ4\" data-linkid=\"5233\" data-shortcode=\"true\"> in ihrem Buch &#8218;The Big Fat Surprise*&#8216;<\/a> aufgegriffen. Vieles begann mit <em>dem Herzinfarkt von Pr\u00e4sident Eisenhower in 1955<\/em>. Die Medizin, vor allem die American Heart Association (AHA) hatte <em>keine <\/em>feste Antwort parat und die Nation war in Panik.<br>Ein Physiologie namens Ancel Keys fand jedoch eine <em>lebhafte <\/em>Antwort:<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ges\u00e4ttigte Fette und erh\u00f6htes Serumcholesterin verstopfen die Gef\u00e4\u00dfe und Herzgef\u00e4\u00dfe. Pflanzen\u00f6le k\u00f6nnen Serumcholesterin nach unten bringen.<\/p><\/blockquote><p>Und <strong>hier war die <em>Cholesterintheorie <\/em>geboren.<\/strong> Bis heute ist diese Theorie weit akzeptiert. Und es stimmt, dass Pflanzen\u00f6le in der Tat Cholesterin senken, jedoch ist diese <em>Fixation auf Cholesterin als Ursache<\/em> nur ein kleiner Teil und ein gro\u00dfes Manko der heutigen Medizin. Laut Ancel Keys funktionert der K\u00f6rper n\u00e4mlich wie die Leitungen eines Haushalts und bei Raumtemperatur harte Fette verstopfen sie. Sehr <em>bildlich <\/em>und klingt <em>erst einmal <\/em>logisch &#8211;<em> nur so funktioniert der K\u00f6rper nicht.<\/em><\/p><h4 class=\"wp-block-heading\">Ancel Keys Studien<\/h4><p>Viele seiner Studien fanden Anklang und Ber\u00fchmtheit im Geiste der Zeit &#8211; die <a href=\"https:\/\/www.crossfit.com\/essentials\/keys-scientific-abandon\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Seven Countries Study<\/a>, und das <a href=\"https:\/\/www.bmj.com\/content\/353\/bmj.i1246\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Minnesota Coronary Experiment<\/a>:<\/p><ul class=\"wp-block-list\"><li>Die erste Studie erkundete die Verbindung von Ern\u00e4hrung und Krankheit, vor allem Nahrungsfetten, Cholesterin und Cardiovasukl\u00e4ren Krankheiten in sieben L\u00e4ndern weltweit.<\/li>\n\n<li>Die Zweite war ein Experiment zum Senken von Cholesterin, indem man ges\u00e4ttigte Fette mit Pflanzen\u00f6len ersetzte im klinischen Umfeld.<\/li><\/ul><p>F\u00fcr mich klingen diese direkt kausalen Verbindungen zu gut zum wahr sein &amp; eher wie der Kerl auf YouTube, der vor seinem Ferrarri stehend nur dir seinen Trick verr\u00e4t, um ohne Arbeit reich zu werden. In Keys Kopf<strong> war Cholesterin der Feind und es zu senken bringt die Rate an Herzkrankheit auch runter<\/strong> &#8211; <em>Fall gel\u00f6st<\/em>! Untermaurt hat er das mit Kirschenpfl\u00fccken &#8211; alle L\u00e4nder wurden aus der &#8218;Seven Country Study&#8216; ausgeschlossen die nicht mit ins Bild passten.<\/p><p>Versteh mich nicht falsch, Keys hatte gute und neue Ideen und brachte damit viel Fokus der \u00d6ffentlichkeit auf den Zusammenhang von Gesundheit und Ern\u00e4hrung. Keys schaffte das durch seine starke und \u00fcberzeugende Art. Schnell war ein Meme geschaffen, das von selbst abhob.<br>Erst sp\u00e4ter wurden weitere Faktoren miteinbezogen, wie Zucker, Diabetes, Fettleibigkeit und Entz\u00fcndung, um das Bild zu vervollst\u00e4ndigen. Anfangs wurde solche Kritik an Keys &amp; der AHA auch vehement unterdr\u00fcckt. Selbst heutzutage besteht dieser Verbindung stark in den K\u00f6pfen der Mediziner.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"1\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Ist Dein LDL Cholesterin stark erh\u00f6ht ist die Guideline Dich auf Statine zu setzen ohne gro\u00dfe andere Abw\u00e4gungen. Kein Wunder, dass Statine ~1 Trillionen USD pro Jahr einfahren. \"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-1\">1<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-1\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"1\">Ist Dein LDL Cholesterin stark erh\u00f6ht ist die Guideline Dich auf Statine zu setzen ohne gro\u00dfe andere Abw\u00e4gungen. Kein Wunder, dass Statine ~1 Trillionen USD pro Jahr einfahren. <\/span> Der vergessene, wahre Feind jedoch ist <em>metabolische Dysfunktion &amp; chronische Entz\u00fcndung.<\/em><\/p><p>Bevor wir uns nun in ein wenig Physiologie st\u00fcrzen, die TL;DR-Zusammenfassung:<\/p><ul class=\"wp-block-list\"><li><strong>Ges\u00e4ttigte Fette waren unser Hauptenergielieferant <\/strong>f\u00fcr den Gro\u00dfteil unserer Evolution. In der Natur ist es die Hauptform der tierischen Fette.<\/li>\n\n<li>Sie sind ges\u00e4ttigt &#8211; haben <strong>nur Einfachverbindungen<\/strong> zwischen den Kohlenstoffatomen.<\/li>\n\n<li>Daher sind sie<strong> satt und reaktionsfaul<\/strong>. Sie haben bereits alles was sie brauchen und bleiben daher auch gerne so.<\/li><\/ul><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h2 class=\"wp-block-heading has-text-align-center\" id=\"a-little-biochemistry-on-fatty-acid-metabolism\"><span style=\"text-decoration: underline;\">Wie l\u00e4uft der Stoffwechsel von Fetts\u00e4uren ab?<\/span><\/h2><p>Um die volle Absurdit\u00e4t zu verstehen, dass ges\u00e4ttigte Fette hochsch\u00e4dlich sind <em>trotz <\/em>unserer Koevolution, m\u00fcssen wir uns ein wenig Physiologie ansehen. Im n\u00e4chsten Teil befassen wir uns also damit<strong>, wie wir aus Fetten Energie gewinnen k\u00f6nnen<\/strong>.<\/p><p>Ich vereinfache das Thema absichtlich und behandle bei weitem nicht alle Aspekte, um es verst\u00e4ndlich zu machen. Wir hier m\u00fcssen nicht alle Puzzleteile verstehen, sondern das oberfl\u00e4chliche &#8218;<em>Warum<\/em>?&#8216;, um<strong> den Nutzen der Prozesse zu verstehen und wie ges\u00e4ttigte Fette sie beeinflussen.<\/strong><\/p><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"wp-block-heading\" id=\"fatty-acid-metabolism\"><span style=\"text-decoration: underline;\">Die Verstoffwechselung von Fetts\u00e4uren<\/span><\/h3><p>Die drei nachfolgenden Prozesse finden in den Mitochondrien Deiner Zellen statt. Um Fette in die Mitochondrien zu bekommen, brauchen wir zwingend Carnitin, das wir nur als <a href=\"https:\/\/ancestrallyhealthy.com\/podcast\/episode-3-zoonaehrstoffe\/\" data-type=\"podcast\" data-id=\"4789\">Zoon\u00e4hrstoff <\/a>aus Tieren erhalten k\u00f6nnen. Kleine Mengen k\u00f6nnen wir bei Bedarf auch selber herstellen.<\/p><h4 class=\"wp-block-heading\" id=\"step-nr-1-ss-oxidation\"><span style=\"text-decoration: underline;\">Schritt Nr.1: \u00df-Oxidation<\/span><\/h4><div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/7\/77\/Metabolism4.jpg\" alt=\"\" width=\"800\" height=\"564\" title=\"\"><figcaption class=\"wp-element-caption\">Image by: Cruithne9, CC BY-SA 4.0 <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\" rel=\"nofollow noopener\" target=\"_blank\">https:\/\/creativecommons.org\/licenses\/by-sa\/4.0<\/a>, via Wikimedia Commons<\/figcaption><\/figure><\/div><p>\u00df-Oxidation<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"2\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Bei Lipid Library, kannst Du noch genauer in die Biochemie einsteigen, wenn meine Ausf\u00fchrung Dir noch nicht reicht.\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-2\">2<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-2\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"2\"><a href=\"https:\/\/lipidlibrary.aocs.org\/chemistry\/physics\/animal-lipids\/fatty-acid-beta-oxidation#:~:text=Fatty%20acid%20%CE%B2%2Doxidation%20is%20the%20process%20by%20which%20fatty,broken%20down%20to%20produce%20energy.&amp;text=The%20long%2Dchain%20acyl%2DCoA%20can%20then%20enter%20the%20fatty,then%20enters%20the%20TCA%20cycle.\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Bei Lipid Library<\/a>, kannst Du noch genauer in die Biochemie einsteigen, wenn meine Ausf\u00fchrung Dir noch nicht reicht.<\/span> <strong>ist der Prozess indem Fetts\u00e4uren kleingeschnitten werden<\/strong>:<\/p><ol class=\"wp-block-list\"><li>W\u00e4hrend eines Kreislaufs der \u00df-Oxidation kannst Du <em>zwei Kohlenstoffatome von der Kette abscheniden <\/em>&#8211; wie mit einer Schere.<\/li>\n\n<li>Das Ergebnis ist <em>ein Molek\u00fcl Acetyl-Coenzyme-A <\/em>(acetyl-CoA), sowie der Rest der gek\u00fcrzten Fetts\u00e4urenkette.<\/li>\n\n<li>Das wird wiederholt, bis die Kette kleingeschnitten ist.<\/li><\/ol><p>Bei ges\u00e4ttigten Fetten mit gleicher Kettenl\u00e4nge, sagen wir mit 16 Kohlenstoffatomen, kannst Du die gesamte Kette kleinschneiden. So erh\u00e4ltst Du 7 CoA und einige andere Cofaktore wie FADH2 &amp; NADH.<br>Unges\u00e4ttigte Fette verhalten sich anders. Du kannst sie zwar komplett zerlegen, verlierst nicht nur Energie, sondern musst sie sogar aktiv aufbringen f\u00fcr bestimmte Umwandlungsenzyme. Je unges\u00e4ttigter eine Fetts\u00e4ure ist, desto <em>weniger <\/em>Cofaktoren (und damit weniger Energie) kannst Du gewinnen.<\/p><p>Zusammenfassend ist das <strong>Ziel der \u00df-Oxidation, die gespeicherte Energie in den Fetten in Cofaktoren umzuwandeln.<\/strong> Wie mit einer Schere machst Du aus einer Kette<em> viele kleine Cofaktoren, die Anteile der Energie halten<\/em>. Diese werden dann in den Citratzyklus gef\u00fcttert.<\/p><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"step-nr-2-the-tca-cycle\"> <span style=\"text-decoration: underline;\">Schritt Nr.2: Der Zitratzyklus<\/span><\/h4><div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/1\/14\/TCACycle_WP78.png\" alt=\"\" width=\"805\" height=\"671\" title=\"\"><figcaption class=\"wp-element-caption\">File by: Alexander Pico, Thomas Kelder, Martijn van Iersel, Kristina Hanspers, Kdahlquist, Nick Fidelman, CC BY 3.0 <a href=\"https:\/\/creativecommons.org\/licenses\/by\/3.0\" rel=\"nofollow noopener\" target=\"_blank\">https:\/\/creativecommons.org\/licenses\/by\/3.0<\/a>, via Wikimedia Commons<\/figcaption><\/figure><\/div><p><a href=\"https:\/\/www.nature.com\/articles\/s41467-019-13668-3\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Der Zitratzyklus<\/a> hat viele Namen wie den TCA-Kreislauf oder Krebszyklus und ist das Trauma vieler Medizinstudenten.<\/p><p>Wie dem auch sei, der Zitratzyklus ist eine komplexe Folge von Reaktionen. <strong>Hier l\u00e4uft die gewonnene Nahrungsenergie aus Fetten (\u00df-Oxidation), Kohlenhydraten (Glykolyse), und ein paar Aminos\u00e4uren zusammen.<\/strong> Alle Makron\u00e4hrstoffe werden in ihren ersten Schritten in acetyl-CoA umgewandelt &#8211; ein Molek\u00fcl Glukose je in 2xCoA, Fette in weitaus mehr je nach Kettenl\u00e4nge und S\u00e4ttigungsgrad:<\/p><ol class=\"wp-block-list\"><li>Acetyl-CoA durchl\u00e4uft den Zitratzyklus, mit<em> dem Ziel noch mehr Cofaktoren herzustellen <\/em>&#8211; haupts\u00e4chlich NADH, FADH2, und bereits etwas ATP.<\/li>\n\n<li>Diese Energietr\u00e4ger gehen dann als N\u00e4chstes \u00fcber in die Atmungskette.<\/li><\/ol><p>Die Atmungskette ist das Ende unserer Reise um zu erfahren wie wir Energie gewinnen. Nach diesem langen Prozess der Umwandlung wird in der Atmungskette endlich Energie in Form von ATP gewonnen, sowie strukturiertes EZ Wasser. Bis hierhin wurden erstaunlicherweise nur Elektronen herumgeschoben &#8211; wahrscheinlich um Deuterium auszuschlie\u00dfen, aber dazu wann anders mehr.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"3\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Die beiden wichtigsten Transporteure hier sind die Redoxpaare von FADH2 und NADH. FAD entsteht aus Vitamin B2, NAD aus Vitamin B3 und NADH ist letzten Endes das Futter, was in die Atmungskette gespeist wird, via Komplex II aka Succinatdehydrogenase. So viel zur Trivia.\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-3\">3<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-3\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"3\">Die beiden wichtigsten Transporteure hier sind die Redoxpaare von FADH2 und NADH. FAD entsteht aus Vitamin B2, NAD aus Vitamin B3 und NADH ist letzten Endes das Futter, was in die Atmungskette gespeist wird, via Komplex II aka Succinatdehydrogenase. So viel zur Trivia.<\/span><\/p><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"step-nr-3-the-electron-transport-chain\"><span style=\"text-decoration: underline;\">Schritt Nr. 3: Die Atmungskette<\/span><\/h4><h5 class=\"wp-block-heading\">Was machen die 5 Komplexe?<\/h5><p>W\u00e4hrend der Atmungskette werden <strong>Protonen von innerhalb der Mitochondrien nach au\u00dferhalb ins Zellplasma gepumpt, in f\u00fcnf Schritten<\/strong>. Dieser negative Energiegradient liefert die Energie, um aus ADP wieder ATP zu generieren, im 5. Schritt der Kette. Es wird &#8218;<em>einfach<\/em>&#8218; ein Phosphor wieder angesteckt an den ADP-Baustein. Ganz sch\u00f6n viel Arbeit f\u00fcr ein Phosphor, oder?<\/p><div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/8\/89\/Mitochondrial_electron_transport_chain%E2%80%94Etc4.svg\" alt=\"\" width=\"802\" height=\"727\" title=\"\"><figcaption class=\"wp-element-caption\">Fvasconcellos 22:35, 9 September 2007 (UTC), Public domain, via Wikimedia Commons<\/figcaption><\/figure><\/div><p>So komisch es klingt, aber das ist die Art und Weise wie alle Lebewesen Energie gewinnen.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"4\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Pflanzen nutzen ein \u00e4hnliches Prinzip, ist aber im Detail anders.\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-4\">4<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-4\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"4\">Pflanzen nutzen ein \u00e4hnliches Prinzip, ist aber im Detail anders.<\/span> Um die Rolle von ges\u00e4ttigten vs. unges\u00e4ttigten Fetten besser zu verstehen, m\u00fcssen wir uns fix die 5 Komplexe ansehen:<\/p><ul class=\"wp-block-list\"><li>Komplex I &amp; II sind die zwei Laderampen.<\/li>\n\n<li>Beide vereinen sich vor Komplex II im sogenannten Coenzym Q-10 Paar.<\/li>\n\n<li>Von hier ist die Reise linear \u00fcber Komplex III zu IV und letztlich Komplex V, wo endlich ATP hergestellt wird.<\/li>\n\n<li>Komplex IV stellt ein spezielles Wasser her, genannt Exklusion-Zone Wasser.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"5\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Einige Theorien deuten gar daraufhin, dass das hier entstehende strukturierte Wasser der Hauptenergietr\u00e4ger der Zelle ist im Zusammenspiel mit Licht.\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-5\">5<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-5\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"5\">Einige Theorien deuten gar daraufhin, dass das hier entstehende strukturierte Wasser der Hauptenergietr\u00e4ger der Zelle ist im Zusammenspiel mit Licht.<\/span><\/li><\/ul><p><br>Ohne dass Protonen nach au\u00dfen gepumpt werden, machst Du kein ATP, da nicht genug Energie aufgestaut wird, um ADP durch Komplex V zu quetschen. Nun erinner Dich an die Kofaktoren. Fette erzeugen am meisten, allen voran Ges\u00e4ttigte. Die Cofaktoren sind letzten Endes das Futter und je mehr Cofaktoren Du hast, desto mehr Protonen pumpst Du nach au\u00dfen. Soweit klar, oder?<\/p><div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h5 class=\"wp-block-heading\">R\u00fcckflie\u00dfender Elektronenfluss<\/h5><p>Was passiert nun aber, <strong>wenn wir zu viele Cofaktoren in die Kette speisen?<\/strong> <\/p><p>Vielleicht, weil Du nicht viel brauchst oder viel Nahrung hattest. Irgendwann kommt es zum Stau, da Komplex I &amp; II wie verr\u00fcckt auf CoQ-10 laden und seine Kapazit\u00e4t aussch\u00f6pfen. Wie ein Stau auf einem Autobahnkreuz mit zwei Laderampen freitags um 16 Uhr. <em>Stillstand<\/em>!<br>Die Zelle regelt den Stau allerdings anders als ungeduldig Musik oder Podcasts zu ballern &#8211; <strong>sie dreht die Richtung um und sendet die angestauten Elektronen direkt zur\u00fcck ins Plasma des Mitochondriums<\/strong>. Der Prozess nennt sich in der Literatur &#8218;<em>Reverse Electron Transport<\/em>&#8218;.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"6\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Role of Mitochondrial Reverse Electron Transport in ROS Signaling: Potential Roles in Health and Disease\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-6\">6<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-6\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"6\"><a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fphys.2017.00428\/full\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Role of Mitochondrial Reverse Electron Transport in ROS Signaling: Potential Roles in Health and Disease<\/a><\/span> <\/p><p>Im Zellplasma reagieren diese freien Elektronen rasant und formen <em>reaktive Sauerstoffspezies<\/em> (ROS), allen voran Superoxid &amp; Wasserstoffperoxid. Diese Kerle sind als freie Radikale sch\u00e4dlich, aber in diesem hochkontrolliertem Umfeld ein <em>gewolltes <\/em>Signal, dass die Zelle satt ist und genug Energie hat. S\u00e4ttigkeit tritt so auf zellul\u00e4rer Ebene ein &#8211; die Zelle wird insulinresistent.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"7\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"https:\/\/high-fat-nutrition.blogspot.com\/2020\/01\/protons-53-formula.html\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-7\">7<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-7\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"7\"><a href=\"https:\/\/high-fat-nutrition.blogspot.com\/2020\/01\/protons-53-formula.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/high-fat-nutrition.blogspot.com\/2020\/01\/protons-53-formula.html<\/a><\/span> Was genau passiert ist dass dieser R\u00fcckfluss ROS kreiert und so das Gleichgewicht diverser Redoxpaare (NADH:NAD+ und ADP:ATP) verschiebt. Das erzeugt potente Signale und aktiviert eine Menge weiteres Zeug. Das ist auch der Grund warum dieses Thema so schnell komplex wird. Alles ist verbunden.<\/p><div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"wp-block-heading\" id=\"it-s-all-about-electrons\"><span style=\"text-decoration: underline;\">Es dreht sich alles um Elektronen<\/span><\/h3><div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-1024x767.jpg\" alt=\"Ungef\u00e4hr so funktionieren Komplex I &amp; II mit dem CoQ Couple in der mitochondrialen Atmungskette.\" class=\"wp-image-3410\" title=\"\" srcset=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-1024x767.jpg 1024w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-600x450.jpg 600w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-300x225.jpg 300w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-768x576.jpg 768w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-734x550.jpg 734w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-1060x794.jpg 1060w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-1536x1151.jpg 1536w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-550x412.jpg 550w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-667x500.jpg 667w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam-1441x1080.jpg 1441w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/Traffic-Jam.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ungef\u00e4hr so funktionieren Komplex I &amp; II mit dem CoQ Couple.<\/figcaption><\/figure><\/div><p>F\u00fcr uns zusammenfassend ist wichtig zu behalten, dass <strong>je mehr CoA in diesen Prozess geschoben wird, desto wahrscheinlicher ein Stau und damit die S\u00e4ttigung der Zelle<\/strong> auftritt.<\/p><p>Auch sind ROS in diesem kontrolliertem Umfeld <em>keine <\/em>schlechte Sache, sie sind <em>einfach ein <\/em>Signal. Das ist auch einer der Gr\u00fcnde, warum ein gro\u00dfes Steak mit Butter Dich weitaus satter macht als eine Pizza oder Chips bei \u00e4hnlicher Energie. Die erste Wahl sind Protein &amp; ges\u00e4ttigte Fette, die zweite Kohlenhydrate und viele unges\u00e4ttigte. Unges\u00e4ttigte Fette schlie\u00dfen diesen Prozess kurz und erschaffen nicht genug Elektronen, um einen Stau zu verursachen &#8211; das ROS Signal bleibt aus\/folgt erst sp\u00e4ter. Auch ver\u00e4ndern PUFAs nicht so stark die Raten der Redoxpaare und so bleiben weitere Signale aus. Glukose beispielsweise erzeugt wenig CoA, auch mehrfach-unges\u00e4ttigte Fette tun dies nicht. Und das ist nur eines der VIELEN Probleme &#8211; <a href=\"https:\/\/ancestrallyhealthy.com\/mehrfach-ungesattigte-fette\/\" data-type=\"post\" data-id=\"3405\">siehe erster Artikel.<\/a><\/p><p>Biochemische Energiegewinnung ist die Geschichte von Elektronen &#8211; aufgenommen von unserem Essen, herumgeschubst von Cofaktoren, zusammengebracht mit Sauerstoff, und verbrannt um Energie zusammen mit EZ Wasser zu erzeugen. Elektronen sind die elektromagnetische W\u00e4hrung der Zelle und eine Grunds\u00e4ule in der <em>Quantengesundheit<\/em>.<\/p><p>Eine klasse Quellen f\u00fcr weitaus mehr Details zu ROS, reduktivem &amp; oxidativem Stress, und wie PUFAs die Atmungskette zerschie\u00dfen ist der Blog von <a href=\"https:\/\/fireinabottle.net\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Brad Marshall von Fire in a Bottle<\/a>.<\/p><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h2 class=\"wp-block-heading has-text-align-center\" id=\"saturated-fats-and-health-we-condemned-the-wrong-one\"><span style=\"text-decoration: underline;\">Ges\u00e4ttigte Fette und Gesundheit &#8211; Wir haben den Falschen angepragert!<\/span><\/h2><p>Mit dieser ganzen Menge Biochemie in unserem Arsenal machen die folgenden Punkte Sinn. Da viele dieser Themen sehr komplex sind, repr\u00e4sentiere ich die TL;DR Fassung. Wenn Du dennoch mehr Infos m\u00f6chtest, empfehle ich Dir w\u00e4rmstens die verlinkten Quellen auszuchecken.<\/p><p>Faszinierenderweise stimmt trotzdem der Punkt, den ich andauernd wiederhole, in seiner ganzen Einfachheit &#8211;<strong> <a href=\"https:\/\/ancestrallyhealthy.com\/newsletter\/\" data-type=\"page\" data-id=\"3605\">lebe wie Deine Vorfahren<\/a> und alle Probleme l\u00f6sen sich von selbst. Wenn wir davon abweichen, leiden wir und zahlen den Preis.<\/strong> So wie bei unserem <em>extrem abgedrehten PUFA Verzehr.<\/em><\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"wp-block-heading\" id=\"benefits-of-saturated-fats\"><span style=\"text-decoration: underline;\">Die Vorteile von ges\u00e4ttigten Fetten in der Nahrung<\/span><\/h3><h4 class=\"wp-block-heading\" id=\"proper-cellular-satiety\">Vern\u00fcnftige S\u00e4ttigung auf zellul\u00e4rer Ebene<\/h4><div class=\"wp-block-image\"><figure class=\"alignright size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-300x169.jpg\" alt=\"Gute ges\u00e4ttigte Fette machen satt.\" class=\"wp-image-3411\" title=\"\" srcset=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-300x169.jpg 300w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-600x338.jpg 600w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-1024x576.jpg 1024w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-768x432.jpg 768w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-978x550.jpg 978w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-1060x596.jpg 1060w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-1536x864.jpg 1536w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-550x309.jpg 550w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak-889x500.jpg 889w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/cut-steak.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Macht definitiv satter als eine Pizza!<\/figcaption><\/figure><\/div><p><strong>Ges\u00e4ttigte Fette speisen die h\u00f6chste Menge pro Molek\u00fcl an Energietr\u00e4gern in die Atmungskette.<\/strong><sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"8\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Hier f\u00fcr die ausf\u00fchrliche Erkl\u00e4rung -&gt; https:\/\/www.bu.edu\/aldolase\/biochemistry2\/18_FattyAcids_2.pdf\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-8\">8<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-8\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"8\">Hier f\u00fcr die ausf\u00fchrliche Erkl\u00e4rung -&gt; <a href=\"https:\/\/www.bu.edu\/aldolase\/biochemistry2\/18_FattyAcids_2.pd\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.bu.edu\/aldolase\/biochemistry2\/18_FattyAcids_2.pd<\/a>f<\/span> Die exakte Menge h\u00e4ngt von der Kettenl\u00e4nge und S\u00e4ttigung ab. Ein R\u00fccktransport tritt auf, wenn wir gen\u00fcgend Elektronen in die Kette hineingeben.<\/p><p>Folglich wird die Zelle gewollt(!) insulinresistent, ROS sind hier das Signal. Systemisch hat das auch starke Effekte auf gewisse Hormone und wie S\u00e4ttigkeit in Deinem Hirn kreiert wird.<\/p><p>Dinge brechen auseinander, wenn Deine Nahrung nicht genug Elektronen erzeugt und kein Stau auftritt, oder erst versp\u00e4tet. Glukose hat es schwer das zu schaffen, so auch unges\u00e4ttigte Fette. Das f\u00fchrt zu einem verf\u00e4lschtem Hungersignal. Deine Zellen werden nicht insulinresistent und behalten ihre Tore sperrangelweit offen. Sie reagieren so stets auf Insulin. So schlie\u00dft man diesem Mechanismus ordentlich kurz, durch evolution\u00e4r-abweichende Mengen und Arten an Energie.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\">Unges\u00e4ttigte Fette sind instabil und zerfallen<\/h4><p>PUFAs sind instabil durch ihre Doppelverbindungen und <strong>reagieren gerne spontan<\/strong>, mit was auch immer in der N\u00e4he ist: Der Prozess hei\u00dft <em>Autooxidation<\/em>. Ein bekanntes Zerfallsprodukt der h\u00e4ufigsten mehrfach-unges\u00e4ttigten Fetts\u00e4ure, namens Linolens\u00e4ure, ist 4-Hydroxynonenal (4-HNE). 4-HNE ist an sich ein eigenes Problem wie man <a href=\"https:\/\/ancestrallyhealthy.com\/mehrfach-ungesattigte-fette\/\" data-type=\"post\" data-id=\"3405\">im ersten Post lesen kann.<\/a><sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"9\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Eine klasse Quelle ist auch die Arbeit von Tucker Goodrich.\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-9\">9<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-9\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"9\">Eine klasse Quelle ist auch die <a href=\"https:\/\/yelling-stop.blogspot.com\/search?q=hne\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Arbeit <\/a>von Tucker Goodrich.<\/span><\/p><p>Eine &#8218;<em>artgerechte<\/em>&#8218; Ern\u00e4hrung f\u00fcr Menschen besteht circa aus 2-4% Linolens\u00e4ure im Verh\u00e4ltnis zur Gesamtenergie aus allen Nahrungsquellen. Moderne Menschen bekommen aber circa 15-30% davon, W\u00e4hrend kleine Mengen durchaus kein Problem sind und auch Aufgaben im K\u00f6rper erf\u00fcllen, ist so ein Ungleichgewicht wie heutzutage dramatisch.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"cell-membrane-health\">Gesundheit der Zellmembranen<\/h4><div class=\"wp-block-image\"><figure class=\"alignright size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-1024x1024.jpg\" alt=\"Ges\u00e4ttigte Fette sind vonn\u00f6ten f\u00fcr intakte Zellmembranen im K\u00f6rper.\" class=\"wp-image-4211\" title=\"\" srcset=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-1024x1024.jpg 1024w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-300x300.jpg 300w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-100x100.jpg 100w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-600x600.jpg 600w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-150x150.jpg 150w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-768x768.jpg 768w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-550x550.jpg 550w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-1060x1060.jpg 1060w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-1536x1536.jpg 1536w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-500x500.jpg 500w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen-1080x1080.jpg 1080w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/05\/zellembranen.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ohne Zellmembranen ein Riesenchaos.<\/figcaption><\/figure><\/div><p>Ohne Zellmembranen geht so ziemlich alles zugrunde im K\u00f6rper.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"10\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Dietary fats influence endoplasmic reticulum membrane\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-10\">10<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-10\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"10\"><a href=\"https:\/\/www.nih.gov\/news-events\/nih-research-matters\/dietary-fats-influence-endoplasmic-reticulum-membrane\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Dietary fats influence endoplasmic reticulum membrane<\/a><\/span> Und Fette sind essenziell f\u00fcr ihre Gesundheit. Ein anderer wichtiger Baustein ist Cholin, welches durch Nahrung &amp; Methylation gewonnen werden muss.<\/p><p><strong>Du brauchst sowohl unges\u00e4ttigte &amp; ges\u00e4ttigte Fette f\u00fcr funktionelle Zellmembranen.<\/strong> Denk einmal \u00fcber beide Fettarten bei Raumtemperatur nach: Ges\u00e4ttigte Fette wie Butter sind fest, w\u00e4hrend stark unges\u00e4ttigte wie Raps\u00f6l fl\u00fcssig ist. Membranen m\u00fcssen so auch ein gutes Gemisch sein, um fluide und dehnbar zu sein &#8211; weder zu fest noch zu flabbelig. Unsere Ern\u00e4hrung beeinflusst das ma\u00dfgeblich.<\/p><p><strong>Wir k\u00f6nnen ges\u00e4ttigtes Fett runterbrechen in unges\u00e4ttigte Fette. <\/strong>Also, wenn wir zu viele ges\u00e4ttigte Fetts\u00e4uren essen, ist es gar kein Problem. Dieser Pfad ist allerdings eine Einbahnstra\u00dfe. Wir k\u00f6nnen keine unges\u00e4ttigten Fetts\u00e4uren s\u00e4ttigen &#8211; in unserer Evolution war dies auch nie vonn\u00f6ten, da alle Nahrungsfette ges\u00e4ttigt sind:<\/p><ul class=\"wp-block-list\"><li>Essen wir also zu viele ges\u00e4ttigte Fette, machen wir einfach die ben\u00f6tigten einfach- und mehrfach-unges\u00e4ttigten Fetts\u00e4uren selber<\/li>\n\n<li>Essen wir zu viele PUFAs reichern wir sie in unserem Fettgewebe und den Zellmembranen an. Membranen werden zu fluide mit allesamt Problemen.<\/li><\/ul><p>Gen\u00fcgend ges\u00e4ttigte Fette mit wenig unges\u00e4ttigten Fetts\u00e4uren unterst\u00fctzen starke Membranen ma\u00dfgeblich. Au\u00dferdem vermeidest Du so die Entz\u00fcndungsreaktionen auf diverse Omega-6-Fetts\u00e4uren. Das hilft vielen aus Anekdoten, auch mir, Hautprobleme und Sonnenbrand zu verhindern. Ich nutze nie Sonnencreme, trainiere im Sommer meist drau\u00dfen, und habe mich seit dem ich<a href=\"https:\/\/ancestrallyhealthy.com\/tierisch-basierte-diaet\/\" data-type=\"post\" data-id=\"3481\"> tierisch-basiert esse<\/a> noch <em>nie <\/em>verbrannt. Auch wenn es nur <em>Anekdata <\/em>ist, ist es richtungsweisend.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"leptin-signalling\">Signalsetzung durch das Hormon Leptin<\/h4><p>Die <strong>Umwandlung von Fetts\u00e4uren von ges\u00e4ttigt zu unges\u00e4ttigt ist abh\u00e4ngig von den beiden Hormonen Insulin &amp; Leptin<\/strong>:<\/p><ul class=\"wp-block-list\"><li>Hast Du eine Menge Insulin im K\u00f6rper am herum kursieren, regt das die Umwandlung in Unges\u00e4ttigte an.<\/li>\n\n<li>Hast Du viel Leptin, verhindert es diese Umwandlung.<\/li><\/ul><p><strong>Leptin ist DAS Steuerhormon schlechthin. Sieh es als Energieanzeiger des K\u00f6rpers an. Unteranderen ist es ein potenter Regulator von Thermogenese<\/strong>, die F\u00e4higkeit Deines K\u00f6rpers selber Hitze zu generieren. Dabei wird Energie anstatt in ATP in Hitze umgewandelt. Vor allem Dein braunes Fettgewebe ist speziell hierzu gemacht. Eine Theorie deutet darauf hin, dass bei guter S\u00e4ttigung Deines K\u00f6rperfettgewebes es weitaus einfacher ist \u00fcbersch\u00fcssige Energie als Hitze abzugeben. Boom, <em>mehr essen, ohne zuzunehmen<\/em>!<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"11\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"A role for brown adipose tissue in diet-induced thermogenesis\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-11\">11<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-11\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"11\"><a href=\"https:\/\/www.nature.com\/articles\/281031a0\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">A role for brown adipose tissue in diet-induced thermogenesis<\/a><\/span><\/p><p>Zu viele Unges\u00e4ttigte regulieren ein Enzym namens <em>Stearyl-CoA-Desaturase<\/em> (SCD1) nach oben.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"12\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\" https:\/\/fireinabottle.net\/torpor-sloth-and-gluttony-scd1-causes-humans-to-store-fat\/ \"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-12\">12<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-12\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"12\"> <a href=\"https:\/\/fireinabottle.net\/torpor-sloth-and-gluttony-scd1-causes-humans-to-store-fat\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/fireinabottle.net\/torpor-sloth-and-gluttony-scd1-causes-humans-to-store-fat\/<\/a><br> <\/span> und hindern so Leptin daran, seine Funktion auszuf\u00fchren, \u00fcbersch\u00fcssige Energie als Hitze abzugeben. Stattdessen muss diese Energie dann gespeichert werden &#8211; urspr\u00fcnglich ist dies ein <em>Winterschlafmechanismus<\/em>.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"13\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\" https:\/\/fireinabottle.net\/this-is-how-linoleic-acid-makes-you-fat-leptin-resistant-and-torpid\/ \"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-13\">13<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-13\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"13\"> <a href=\"https:\/\/fireinabottle.net\/this-is-how-linoleic-acid-makes-you-fat-leptin-resistant-and-torpid\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/fireinabottle.net\/this-is-how-linoleic-acid-makes-you-fat-leptin-resistant-and-torpid\/<\/a><br> <\/span>.<\/p><p>F\u00fcr mehr Infos zu diesem immens weitl\u00e4ufigen Thema kann ich Brad Marshall&#8217;s <a href=\"https:\/\/fireinabottle.net\/the-scd1-theory-of-obesity-part-2-the-post-obese-metabolism-and-what-you-can-do-about-it\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">SCD1 Theory of Obesity<\/a>, als Startpunkt empfehlen.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"hormonal-building-blocks\">Elementare Bausteine der Hormone<\/h4><p>Ges\u00e4ttigte Fette, wie auch Cholesterin, sind <strong>fundamental wichtig als Bausteine f\u00fcr alle Steroidhormone und viele weitere wie auch Vitamin D<\/strong>. Der Wechsel zu einer pflanzenbasierten Ern\u00e4hrung, mit wenig Cholesterin und ges\u00e4ttigten Fetten wiederum zerschie\u00dft Deine Steroidhormone wie Sexualhormone, Vitamin D, oder Kortikoide.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"14\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\" Saturated Fat Ingestion regulates Androgen Release \"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-14\">14<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-14\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"14\"> <a href=\"https:\/\/academic.oup.com\/biomedgerontology\/article\/63\/11\/1260\/759439\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Saturated Fat Ingestion regulates Androgen Release<\/a> <\/span> <\/p><p>Anst\u00e4ndige Werte von Sexualhormonen sind wichtig in unserer modernen Welt voll mit \u00f6strogenartigen Umweltgiften. Kein Wunder, dass durch all diese Faktoren zusammen die Testosteronwerte in die Keller schie\u00dfen und heutzutage ein Mann nicht nur ein Mann ist, sondern sein kann, was auch immer er sich f\u00fchlt.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"15\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\" testosterone and Cortisol in Relation to exercise and dietary fats + dietary and serum sex hormones in healthy men\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-15\">15<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-15\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"15\"> <a href=\"https:\/\/journals.physiology.org\/doi\/full\/10.1152\/jappl.1997.82.1.49\" rel=\"nofollow noopener\" target=\"_blank\">testosterone and Cortisol in Relation to exercise and dietary fats<\/a> + <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/6538617\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">dietary and serum sex hormones in healthy men<\/a><\/span><\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"wp-block-heading\" id=\"public-fears-targetted-against-saturated-fats\"><span style=\"text-decoration: underline;\">H\u00e4ufige &#8218;\u00c4ngste&#8216; in Bezug auf ges\u00e4ttigte Fette<\/span><\/h3><p>Leider ist es nicht nur Unwissen, was Menschen vom Konsum gen\u00fcgend tierischer ges\u00e4ttigter Fette abh\u00e4lt, sondern auch Panik, die \u00fcber viele \u00f6ffentliche Kan\u00e4le verbreitet wurde. Viele dieser \u00c4ngste sind tief in den K\u00f6pfen verankert &#8211; Memes in Aktion.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"fear-no-1-elevated-cholesterol-atherosclerosis\">Bedenken Nr. 1 &#8211; Erh\u00f6tes Blutcholesterin &amp; Arteriosklerose<\/h4><p>Nach Ancel Keys Hypothese verstopft Cholesterin Gef\u00e4\u00dfe wie Fette im Heimrohrsystem. Und Cholesterin wird, erh\u00f6ht durch ges\u00e4ttigte Fette. Also m\u00fcssen ges\u00e4ttigte Fette gemieden und Cholesterin heruntergedr\u00fcckt werden um jeden Preis. Der klassische Fehler von Kausation &amp; Korrelation.<\/p><p>Seine Antwort darauf waren <em>Pflanzen\u00f6le<\/em>, da unges\u00e4ttigte Fette durchaus Cholesterin herunterdr\u00fccken. Nur leider bringt es nichts und macht die Lage um ein vielfaches schlimmer.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"16\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Low-Fat &#8218;Healthy&#8216; Diets increase plasma levels of OxLDL and LP(a)\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-16\">16<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-16\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"16\"><a href=\"https:\/\/www.ahajournals.org\/doi\/10.1161\/01.ATV.0000118014.49565.fc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Low-Fat &#8218;Healthy&#8216; Diets increase plasma levels of OxLDL and LP(a)<\/a><\/span> LDL Cholesterin wurde verteufelt, da es in vielen Gef\u00e4\u00dfplaques anzutreffen ist. Und das ist wahr. Mein Problem ist, dass LDL nur wegen seiner Anwesenheit in diesen Plaques als Ausl\u00f6ser verteufelt wird. Das stimmt nicht. <strong>Genauso wenig wie ein Feuerwehrmann jeden Brand legt, nur weil er immer anwesend ist, ist LDL nicht verantwortlich f\u00fcr Plaques. <\/strong>Verantwortlich ist eine vorher vorhandene Entz\u00fcndung, durch die LDL dort stecken bleibt. Auch spielen oxidierte LDL-Partikel eine gro\u00dfe Rolle. Und die Hauptverantwortlichen daf\u00fcr sind PUFAs.<\/p><p>Dem entgegen stehen auch Menschen, die ketogen essen, wie jeder auf einer Carnivore Di\u00e4t. Cholesterin&#8217;s Aufgabe ist es <em>Fette zu transportieren im Blut<\/em> &#8211; wenn Du mehr oder gar haupts\u00e4chlich Fette ist brauchst Du auch logischerweise mehr Transporter. Logisch, oder?<\/p><p>Zusammenfassend k\u00f6nnen wir klar sagen, dass Ancel Keys <em>falsch lag<\/em>. Auch wenn er wichtige Arbeit leistete und die Zusammenh\u00e4nge von Ern\u00e4hrung und Krankheit publik machte, plagen uns seine Memes heute noch, gar das gesamte &#8218;Krankheitsmanagementsystem&#8216;. Habe daher keine Angst vor ges\u00e4ttigten Fetten. Habe<em> Angst vor chronischer Entz\u00fcndung<\/em>. F\u00fcr mehr zu diesem Thema kann ich Dir die Arbeite von Blutlipidforscher <a href=\"https:\/\/cholesterolcode.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Dave Feldman<\/a> empfehlen.<\/p><div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h4 class=\"wp-block-heading\" id=\"fear-nr-2-non-alcoholic-fatty-liver-disease\">Bedenken Nr. 2 &#8211; Nicht-Alkohlische Fettleber<\/h4><div class=\"wp-block-image\"><figure class=\"alignright size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-1024x683.jpg\" alt=\"Fette machen nicht die Leber fett, metabolische Dysfunktion macht dies.\" class=\"wp-image-3421\" title=\"\" srcset=\"https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-1024x683.jpg 1024w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-600x400.jpg 600w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-300x200.jpg 300w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-768x512.jpg 768w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-825x550.jpg 825w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-1060x707.jpg 1060w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-1536x1024.jpg 1536w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-550x367.jpg 550w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-750x500.jpg 750w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat-1620x1080.jpg 1620w, https:\/\/ancestrallyhealthy.com\/wp-content\/uploads\/2022\/01\/butter-as-saturated-fat.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Macht nicht die Leber fett.<\/figcaption><\/figure><\/div><p>Viele denken, viel Fett macht die Leber fett. Leider klappt es so nicht. Das war auch ein bekanntes Meme im Fettwahnsinn der Ern\u00e4hrungsrichtlinien der 90er.<\/p><p>Wir wissen, dass bestimmte Krankheiten dazu f\u00fchren, dass die Leber Fett einlagert. Das sollte nicht passieren.<\/p><ul class=\"wp-block-list\"><li>Beispielsweise andauernder Alkoholkonsum f\u00fchrt zu alkoholischer Fettleber. <\/li>\n\n<li>Auch kann es auftreten im Kontext von metabolischer Krankheit wie Diabetes und wird nicht-alkohlbedinge Fettleber genannt (NAFLD)<\/li><\/ul><p>Im Zusammenhang von NAFLD kannst Du es Dir als Rettungsversuch vorstellen. Im Blut steigen die Triglyceridwerte stark an und um dieses Problem zu dr\u00fccken, lagert die Leber Fette in ihr Gewebe ein. So sinken die Blutwerte. Es ist eine <em>Ultima Ratio.<\/em> Es ist eine Folge von langer metabolischer Dysfunktion. Der Konsum von ges\u00e4ttigten Fetts\u00e4uren steht zum Gl\u00fcck nicht um Zusammenhang damit.<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"17\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Long-term SAF diet does not induce NASH\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-17\">17<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-17\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"17\"><a href=\"https:\/\/nutritionandmetabolism.biomedcentral.com\/articles\/10.1186\/1743-7075-4-4\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Long-term SAF diet does not induce NASH<\/a><\/span> Vielmehr ist <strong>NAFLD mit metabolischer Dysfunktion zusammenzuf\u00fchren und nicht mit dem Konsum von zu viel Fett.<\/strong><sup class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"18\" data-mfn-post-scope=\"00000000527c7272000000004b0ef1ff_3420\"><a href=\"javascript:void(0)\"  title=\"Reversal of obesity and liver steatosis in mice via inhibition of aryl hydrocarbon receptor and altered gene expression of CYP1B1, PPAR\u03b1, SCD1, and osteopontin &amp; Stearoyl-CoA desaturase 1 deficiency protects mice from immune-mediated liver injury\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-18\">18<\/a><\/sup><span id=\"mfn-content-00000000527c7272000000004b0ef1ff_3420-18\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"18\"><a href=\"https:\/\/www.nature.com\/articles\/s41366-019-0512-z\" rel=\"nofollow noopener\" target=\"_blank\">Reversal of obesity and liver steatosis in mice via inhibition of aryl hydrocarbon receptor and altered gene expression of CYP1B1, PPAR\u03b1, SCD1, and osteopontin<\/a> &amp; <a href=\"https:\/\/www.nature.com\/articles\/labinvest2008105\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Stearoyl-CoA desaturase 1 deficiency protects mice from immune-mediated liver injury<\/a><\/span><\/p><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h2 class=\"wp-block-heading has-text-align-center\" id=\"maybe-not-so-bad-at-all\"><span style=\"text-decoration: underline;\">Am Ende doch nicht <em>so <\/em>schlimm?!<\/span><\/h2><p>Am Schluss k\u00f6nnen wir sagen, dass viele Informationen auf schlechter Wissenschaft, Profitgier seitens P&amp;G und der AHA, und zeitgem\u00e4\u00dfen Panikreaktionen basiert waren. Leider sind solche Memes schwer zu t\u00f6ten. Bis heute halten sie sich trotz \u00fcberw\u00e4ltigenden Gegenbeweisen hart im Kopf der Gesellschaft, der Profis und sogar den Empfehlungen.<\/p><p>Ganz ehrlich w\u00fcrde es mich auch erstaunen, wenn eine Lebensmittelgruppe, mit der wir \u00fcber Millionen von Jahren zusammen als Spezies aufgewachsen sind, sch\u00e4dlich f\u00fcr uns w\u00e4re. <strong>Das macht NULL Sinn. <\/strong>Bullshit! Die evolution\u00e4re Sicht hat Recht und am Ende ist es wirklich simpel. Deine Vorfahren h\u00e4tten niemals Pflanzen\u00f6le erstellen k\u00f6nnen.<\/p><p>Ges\u00e4ttigtes Fett ist gar gesund und f\u00fchrt zu vielen guten Auskommen. Auch kann Dein K\u00f6rper bestens damit umgehen und das daraus machen, was er braucht. Es ist ein wichtiger Baustein f\u00fcr viele fundamental Dinge wie Zellmembranen und Hormone. Habe also keine Angst vor Ihnen und lasse sie den Gro\u00dfteil Deiner Fette sein. <a href=\"https:\/\/ancestrallyhealthy.com\/mehrfach-ungesattigte-fette\/\" data-type=\"post\" data-id=\"3405\">Meide unges\u00e4ttigte Fette<\/a> und eliminiere Pflanzen\u00f6le fanatisch.<\/p><p>Mache dies und Du gehst einen gro\u00dfen Schritt hin zu optimaler Gesundheit.<\/p><div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img decoding=\"async\" src=\"https:\/\/img.kevinjuehlke.com\/wp-content\/uploads\/2020\/09\/18221054\/Signature-KJ-transparent.png\" alt=\"This is my Signature\" class=\"wp-image-6538\" title=\"\"><\/figure><\/div><div style=\"height:188px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><h3 class=\"modern-footnotes-list-heading \">Fu\u00dfnoten & Quellen<\/h3><ul class=\"modern-footnotes-list \"><li><span>1<\/span><div>Ist Dein LDL Cholesterin stark erh\u00f6ht ist die Guideline Dich auf Statine zu setzen ohne gro\u00dfe andere Abw\u00e4gungen. Kein Wunder, dass Statine ~1 Trillionen USD pro Jahr einfahren. <\/div><\/li><li><span>2<\/span><div><a href=\"https:\/\/lipidlibrary.aocs.org\/chemistry\/physics\/animal-lipids\/fatty-acid-beta-oxidation#:~:text=Fatty%20acid%20%CE%B2%2Doxidation%20is%20the%20process%20by%20which%20fatty,broken%20down%20to%20produce%20energy.&amp;text=The%20long%2Dchain%20acyl%2DCoA%20can%20then%20enter%20the%20fatty,then%20enters%20the%20TCA%20cycle.\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Bei Lipid Library<\/a>, kannst Du noch genauer in die Biochemie einsteigen, wenn meine Ausf\u00fchrung Dir noch nicht reicht.<\/div><\/li><li><span>3<\/span><div>Die beiden wichtigsten Transporteure hier sind die Redoxpaare von FADH2 und NADH. FAD entsteht aus Vitamin B2, NAD aus Vitamin B3 und NADH ist letzten Endes das Futter, was in die Atmungskette gespeist wird, via Komplex II aka Succinatdehydrogenase. So viel zur Trivia.<\/div><\/li><li><span>4<\/span><div>Pflanzen nutzen ein \u00e4hnliches Prinzip, ist aber im Detail anders.<\/div><\/li><li><span>5<\/span><div>Einige Theorien deuten gar daraufhin, dass das hier entstehende strukturierte Wasser der Hauptenergietr\u00e4ger der Zelle ist im Zusammenspiel mit Licht.<\/div><\/li><li><span>6<\/span><div><a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fphys.2017.00428\/full\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Role of Mitochondrial Reverse Electron Transport in ROS Signaling: Potential Roles in Health and Disease<\/a><\/div><\/li><li><span>7<\/span><div><a href=\"https:\/\/high-fat-nutrition.blogspot.com\/2020\/01\/protons-53-formula.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/high-fat-nutrition.blogspot.com\/2020\/01\/protons-53-formula.html<\/a><\/div><\/li><li><span>8<\/span><div>Hier f\u00fcr die ausf\u00fchrliche Erkl\u00e4rung -&gt; <a href=\"https:\/\/www.bu.edu\/aldolase\/biochemistry2\/18_FattyAcids_2.pd\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.bu.edu\/aldolase\/biochemistry2\/18_FattyAcids_2.pd<\/a>f<\/div><\/li><li><span>9<\/span><div>Eine klasse Quelle ist auch die <a href=\"https:\/\/yelling-stop.blogspot.com\/search?q=hne\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Arbeit <\/a>von Tucker Goodrich.<\/div><\/li><li><span>10<\/span><div><a href=\"https:\/\/www.nih.gov\/news-events\/nih-research-matters\/dietary-fats-influence-endoplasmic-reticulum-membrane\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Dietary fats influence endoplasmic reticulum membrane<\/a><\/div><\/li><li><span>11<\/span><div><a href=\"https:\/\/www.nature.com\/articles\/281031a0\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">A role for brown adipose tissue in diet-induced thermogenesis<\/a><\/div><\/li><li><span>12<\/span><div> <a href=\"https:\/\/fireinabottle.net\/torpor-sloth-and-gluttony-scd1-causes-humans-to-store-fat\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/fireinabottle.net\/torpor-sloth-and-gluttony-scd1-causes-humans-to-store-fat\/<\/a><br> <\/div><\/li><li><span>13<\/span><div> <a href=\"https:\/\/fireinabottle.net\/this-is-how-linoleic-acid-makes-you-fat-leptin-resistant-and-torpid\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/fireinabottle.net\/this-is-how-linoleic-acid-makes-you-fat-leptin-resistant-and-torpid\/<\/a><br> <\/div><\/li><li><span>14<\/span><div> <a href=\"https:\/\/academic.oup.com\/biomedgerontology\/article\/63\/11\/1260\/759439\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Saturated Fat Ingestion regulates Androgen Release<\/a> <\/div><\/li><li><span>15<\/span><div> <a href=\"https:\/\/journals.physiology.org\/doi\/full\/10.1152\/jappl.1997.82.1.49\" rel=\"nofollow noopener\" target=\"_blank\">testosterone and Cortisol in Relation to exercise and dietary fats<\/a> + <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/6538617\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">dietary and serum sex hormones in healthy men<\/a><\/div><\/li><li><span>16<\/span><div><a href=\"https:\/\/www.ahajournals.org\/doi\/10.1161\/01.ATV.0000118014.49565.fc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Low-Fat &#8218;Healthy&#8216; Diets increase plasma levels of OxLDL and LP(a)<\/a><\/div><\/li><li><span>17<\/span><div><a href=\"https:\/\/nutritionandmetabolism.biomedcentral.com\/articles\/10.1186\/1743-7075-4-4\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Long-term SAF diet does not induce NASH<\/a><\/div><\/li><li><span>18<\/span><div><a href=\"https:\/\/www.nature.com\/articles\/s41366-019-0512-z\" rel=\"nofollow noopener\" target=\"_blank\">Reversal of obesity and liver steatosis in mice via inhibition of aryl hydrocarbon receptor and altered gene expression of CYP1B1, PPAR\u03b1, SCD1, and osteopontin<\/a> &amp; <a href=\"https:\/\/www.nature.com\/articles\/labinvest2008105\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Stearoyl-CoA desaturase 1 deficiency protects mice from immune-mediated liver injury<\/a><\/div><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Ges\u00e4ttigte Fette mussten viel Kritik einstecken \u00fcber die letzten Jahrzehnte. Sind sie tats\u00e4chlich so schlecht f\u00fcr uns? Ich w\u00fcrde sie gar als gesund bezeichnen.<\/p>\n","protected":false},"author":1,"featured_media":3421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,2],"tags":[74,77,167,82,159,157],"class_list":["post-3420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vorteile-von-fleisch","category-animal-based-diet","tag-ancestral-health","tag-animal-based-diet","tag-ernahrungswissenschaften","tag-nutritional-science","tag-tierisch-basierte-ernahrung","tag-zoonaehrstoffe-de-2","is-cat-link-solid-light is-cat-link-rounded"],"_links":{"self":[{"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/posts\/3420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/comments?post=3420"}],"version-history":[{"count":0,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/posts\/3420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/media\/3421"}],"wp:attachment":[{"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/media?parent=3420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/categories?post=3420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrallyhealthy.com\/de\/wp-json\/wp\/v2\/tags?post=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}